{"id":6937,"date":"2023-05-17T10:50:23","date_gmt":"2023-05-17T08:50:23","guid":{"rendered":"https:\/\/www.nikolaidis.eu\/?post_type=product&#038;p=6937"},"modified":"2023-08-25T14:17:51","modified_gmt":"2023-08-25T12:17:51","slug":"brushcutter-honda-umk-435-ueet","status":"publish","type":"product","link":"https:\/\/www.nikolaidis.eu\/en\/product\/agriculture\/brushcutters\/bicycle-handle\/petrol-bicycle-handle\/brushcutter-honda-umk-435-ueet\/","title":{"rendered":"Brushcutter Honda UMK 435 UEET"},"content":{"rendered":"<p>The UMK 435 UEET brushcutters, powered by the GX35 engine, are quiet and easy to use. No matter how difficult the job &#8211; you have an ally with you. Honda&#8217;s four-stroke engines are not only the most compact and reliable of their kind, but they help reduce noise, vibration and emissions. They are extremely versatile machines and feature adjustable harnesses for maximum comfort.<\/p>\n<div class=\"col-md-6\">\n<div class=\"grey-box-product content-txt h-100\">\n<h5 class=\"heading-title\">ADVANTAGES<\/h5>\n<ul>\n<li class=\"heading-title\">Low fuel consumption<\/li>\n<li class=\"heading-title\">Easy to start &#8211; Decompression system<\/li>\n<li class=\"heading-title\">Operation with unleaded petrol &#8211; no mixing with oil<\/li>\n<li class=\"heading-title\">Low exhaust emissions<\/li>\n<li class=\"heading-title\">Quiet operation<\/li>\n<li class=\"heading-title\">Low vibration for comfortable use<\/li>\n<li class=\"heading-title\">360\u00b0 lubrication<\/li>\n<li class=\"heading-title\">Fast acceleration and excellent torque for demanding jobs<\/li>\n<li class=\"heading-title\">Ergonomically designed and positioned controls<\/li>\n<li class=\"heading-title\">Handlebar &#8211; Bicycle type<\/li>\n<li class=\"heading-title\">Bumper designed to provide increased visibility to the operator<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"page\" title=\"Page 5\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Honda GX 35 four-stroke engine<\/p>\n<p>Cubic capacity: 35 cc<br \/>\nPower: 1.35 hp<br \/>\nEngine torque: 1.6 Nm<br \/>\nWeight: 7.53 kg<br \/>\nIncluded: Nylon line head, blade, double professional harness<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":22347,"template":"","meta":[],"product_cat":[1242,1245,1246,1206],"product_tag":[],"class_list":{"0":"post-6937","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brushcutters","7":"product_cat-bicycle-handle","8":"product_cat-petrol-bicycle-handle","9":"product_cat-agriculture","11":"first","12":"custom-contact","13":"sale","14":"featured","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brushcutter Honda UMK 435 UEET - Nikolaidis Tools<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nikolaidis.eu\/product\/\u03b1\u03b3\u03c1\u03bf\u03c4\u03b9\u03ba\u03ac\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03ac\/\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03b2\u03b5\u03bd\u03b6\u03af\u03bd\u03b7\u03c2-\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03cc-honda-umk-435-ueet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brushcutter Honda UMK 435 UEET - Nikolaidis Tools\" \/>\n<meta property=\"og:description\" content=\"Honda GX 35 four-stroke engine  Cubic capacity: 35 cc Power: 1.35 hp Engine torque: 1.6 Nm Weight: 7.53 kg Included: Nylon line head, blade, double professional harness\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nikolaidis.eu\/product\/\u03b1\u03b3\u03c1\u03bf\u03c4\u03b9\u03ba\u03ac\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03ac\/\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03b2\u03b5\u03bd\u03b6\u03af\u03bd\u03b7\u03c2-\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03cc-honda-umk-435-ueet\/\" \/>\n<meta property=\"og:site_name\" content=\"Nikolaidis Tools\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nikolaidis.store\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T12:17:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"348\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/\",\"url\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/\",\"name\":\"Brushcutter Honda UMK 435 UEET - Nikolaidis Tools\",\"isPartOf\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png\",\"datePublished\":\"2023-05-17T08:50:23+00:00\",\"dateModified\":\"2023-08-25T12:17:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage\",\"url\":\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png\",\"contentUrl\":\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png\",\"width\":1095,\"height\":1095},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\/\/www.nikolaidis.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.nikolaidis.eu\/en\/eshop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brushcutter Honda UMK 435 UEET\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nikolaidis.eu\/#website\",\"url\":\"https:\/\/www.nikolaidis.eu\/\",\"name\":\"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2\",\"description\":\"Agricultural, washing and industrial machinery for the amateur and professional\",\"publisher\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nikolaidis.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nikolaidis.eu\/#organization\",\"name\":\"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2\",\"url\":\"https:\/\/www.nikolaidis.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nikolaidis.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/logo6_b_teliko_big.png\",\"contentUrl\":\"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/logo6_b_teliko_big.png\",\"width\":4214,\"height\":4593,\"caption\":\"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2\"},\"image\":{\"@id\":\"https:\/\/www.nikolaidis.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nikolaidis.store\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brushcutter Honda UMK 435 UEET - Nikolaidis Tools","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nikolaidis.eu\/product\/\u03b1\u03b3\u03c1\u03bf\u03c4\u03b9\u03ba\u03ac\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03ac\/\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03b2\u03b5\u03bd\u03b6\u03af\u03bd\u03b7\u03c2-\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03cc-honda-umk-435-ueet\/","og_locale":"en_US","og_type":"article","og_title":"Brushcutter Honda UMK 435 UEET - Nikolaidis Tools","og_description":"Honda GX 35 four-stroke engine  Cubic capacity: 35 cc Power: 1.35 hp Engine torque: 1.6 Nm Weight: 7.53 kg Included: Nylon line head, blade, double professional harness","og_url":"https:\/\/www.nikolaidis.eu\/product\/\u03b1\u03b3\u03c1\u03bf\u03c4\u03b9\u03ba\u03ac\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03ac\/\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03b2\u03b5\u03bd\u03b6\u03af\u03bd\u03b7\u03c2-\u03c0\u03bb\u03b1\u03ca\u03bd\u03ae\u03c2-\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2\/\u03c7\u03bf\u03c1\u03c4\u03bf\u03ba\u03bf\u03c0\u03c4\u03b9\u03ba\u03cc-honda-umk-435-ueet\/","og_site_name":"Nikolaidis Tools","article_publisher":"https:\/\/www.facebook.com\/nikolaidis.store","article_modified_time":"2023-08-25T12:17:51+00:00","og_image":[{"width":348,"height":446,"url":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/","url":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/","name":"Brushcutter Honda UMK 435 UEET - Nikolaidis Tools","isPartOf":{"@id":"https:\/\/www.nikolaidis.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage"},"image":{"@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png","datePublished":"2023-05-17T08:50:23+00:00","dateModified":"2023-08-25T12:17:51+00:00","breadcrumb":{"@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#primaryimage","url":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png","contentUrl":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/HONDA_UMK_435_UEET.png","width":1095,"height":1095},{"@type":"BreadcrumbList","@id":"https:\/\/www.nikolaidis.eu\/product\/%ce%b1%ce%b3%cf%81%ce%bf%cf%84%ce%b9%ce%ba%ce%ac\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%ce%ac\/%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%ce%b2%ce%b5%ce%bd%ce%b6%ce%af%ce%bd%ce%b7%cf%82-%cf%80%ce%bb%ce%b1%cf%8a%ce%bd%ce%ae%cf%82-%cf%83%cf%84%ce%ae%cf%81%ce%b9%ce%be%ce%b7%cf%82\/%cf%87%ce%bf%cf%81%cf%84%ce%bf%ce%ba%ce%bf%cf%80%cf%84%ce%b9%ce%ba%cf%8c-honda-umk-435-ueet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/www.nikolaidis.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.nikolaidis.eu\/en\/eshop\/"},{"@type":"ListItem","position":3,"name":"Brushcutter Honda UMK 435 UEET"}]},{"@type":"WebSite","@id":"https:\/\/www.nikolaidis.eu\/#website","url":"https:\/\/www.nikolaidis.eu\/","name":"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2","description":"Agricultural, washing and industrial machinery for the amateur and professional","publisher":{"@id":"https:\/\/www.nikolaidis.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nikolaidis.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nikolaidis.eu\/#organization","name":"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2","url":"https:\/\/www.nikolaidis.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nikolaidis.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/logo6_b_teliko_big.png","contentUrl":"https:\/\/www.nikolaidis.eu\/wp-content\/uploads\/logo6_b_teliko_big.png","width":4214,"height":4593,"caption":"\u039c\u03b7\u03c7\u03b1\u03bd\u03ae\u03bc\u03b1\u03c4\u03b1 \u039d\u03b9\u03ba\u03bf\u03bb\u03b1\u0390\u03b4\u03b7\u03c2"},"image":{"@id":"https:\/\/www.nikolaidis.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nikolaidis.store"]}]}},"_links":{"self":[{"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/product\/6937"}],"collection":[{"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/media\/22347"}],"wp:attachment":[{"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/media?parent=6937"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/product_cat?post=6937"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.nikolaidis.eu\/en\/wp-json\/wp\/v2\/product_tag?post=6937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}